{"id":5616,"date":"2022-02-28T14:02:54","date_gmt":"2022-02-28T14:02:54","guid":{"rendered":"https:\/\/www.dmklawyers.com\/?p=5616"},"modified":"2022-05-09T19:11:04","modified_gmt":"2022-05-09T19:11:04","slug":"work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022","status":"publish","type":"post","link":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/","title":{"rendered":"Work to begin on the first hotels in Pedernales in mid-2022"},"content":{"rendered":"\n<p>El presidente de la Rep\u00fablica,\u00a0Luis Abinader, dijo este domingo que el\u00a0desarrollo tur\u00edstico\u00a0de\u00a0Pedernales\u00a0es una de las apuestas m\u00e1s importantes de su gesti\u00f3n, porque, de acuerdo al mandatario, transformar\u00e1 la vida de miles de personas de la provincia de\u00a0Pedernales\u00a0y de toda la regi\u00f3n Sur del pa\u00eds.<\/p>\n\n<p>\u201cEste proyecto, que inicia en\u00a0Cabo Roj<strong>o<\/strong>, y en el que hemos puesto todo nuestro empe\u00f1o, marcar\u00e1 un antes y un despu\u00e9s en el\u00a0desarrollo tur\u00edstico\u00a0de nuestra naci\u00f3n\u201d, expres\u00f3.<\/p>\n\n<p>Explic\u00f3 que el proyecto se har\u00e1n en cuatro fases, durante un periodo promedio total de 10 a\u00f1os, y con una inversi\u00f3n estimada de 2,245 millones de d\u00f3lares.<\/p>\n\n<p>Agreg\u00f3 que en la primera fase se estipula una inversi\u00f3n de 1,300 millones de d\u00f3lares para la construcci\u00f3n de 4,700 habitaciones, que se convertir\u00e1n en 12,000 al final del proyecto.<\/p>\n\n<p>\u201cOcho hoteles iniciar\u00e1n sus operaciones durante la apertura de esa primera fase, para lo cual ya las cadenas hoteleras Hilton, Marriott, Sunwing, AmResorts, Iberostar Group y Karisma Hotels &amp; Resort han firmado una carta de compromiso para empezar la construcci\u00f3n a partir de mediados de este a\u00f1o\u201d, explic\u00f3 Abinader en su alocuci\u00f3n ante la Asamblea General, donde este 27 de febrero, D\u00eda de la independencia Nacional, rinde cuentas a la naci\u00f3n.<\/p>\n\n<p>Indic\u00f3 que en esta primera fase se construir\u00e1 tambi\u00e9n un aeropuerto internacional, un centro comercial y se concluir\u00e1n todas las obras de infraestructuras b\u00e1sicas necesarias, como la construcci\u00f3n de un acueducto, una planta de tratamiento de aguas y un sistema de transmisi\u00f3n el\u00e9ctrica.<\/p>\n\n<p>\u201cEl desarrollo de este nuevo y espectacular polo tur\u00edstico crear\u00e1 cerca de 20,000 empleos directos y m\u00e1s de 50,000 indirectos, con todo lo que esto supone para el dinamismo econ\u00f3mico de la regi\u00f3n\u201d, precis\u00f3 en mandatario.<\/p>\n\n<h3 class=\"wp-block-heading\">Miches en la regi\u00f3n Este de la Rep\u00fablica Dominicana<\/h3>\n\n<p>El presidente Abinader tambi\u00e9n se refiri\u00f3 al municipio de Miches, provincia de El Seibo. Explic\u00f3 que se va a pasar de un hotel en operaci\u00f3n a por lo menos cuatro m\u00e1s en construcci\u00f3n con inauguraci\u00f3n en este mismo a\u00f1o 2022, 2023 y 2024.<\/p>\n\n<p>Junto a ProMiches, apunt\u00f3, se desarrollar\u00e1 un m\u00e1ster plan para la regi\u00f3n, priorizando el cuidado del medioambiente e identificando la inversi\u00f3n p\u00fablica necesaria.<\/p>\n\n<p>\u201cA d\u00eda de hoy, distintos proyectos han iniciado o continuado sus procesos de desarrollo, entre ellos el Four Season Tropicana, Hotel Zem\u00ed, Viva Miches y Secrets playa Esmeralda\u201d, dijo el mandatario.<\/p>\n\n<p>Agreg\u00f3 que estos proyectos representan m\u00e1s de 1,000 millones de d\u00f3lares en inversiones, unas 2,900 habitaciones hoteleras y 2,000 habitaciones inmobiliarias, y m\u00e1s de 10,000 empleos durante el proceso de desarrollo y 6,000 empleos para zona durante la operaci\u00f3n.<\/p>\n\n<p>Adem\u00e1s, revel\u00f3 que en la zona norte se iniciar\u00e1 un proyecto totalmente innovador, de la mano de aliados comprometidos con la Rep\u00fablica Dominicana. \u201cLes hablo del proyecto de Punta Bergant\u00edn cuyos dise\u00f1os est\u00e1n ya listos y haremos el lanzamiento pr\u00f3ximamente\u201d.<\/p>\n\n<h3 class=\"wp-block-heading\">El\u00a0<strong>turismo<\/strong>\u00a0en 2021<\/h3>\n\n<p>El presidente Abinader record\u00f3 que, en el sector tur\u00edstico, por ejemplo, durante el \u00faltimo trimestre del a\u00f1o se superaron los niveles prepandemia y diciembre fue el de mayores llegadas de la historia al pa\u00eds con m\u00e1s de 720 mil visitantes.<\/p>\n\n<p>Dijo que la llegada de turistas signific\u00f3 m\u00e1s de 5,400 millones en divisas, sumando estabilidad cambiaria ante un entorno de precios externos elevados.<\/p>\n\n<p>\u201cActuamos con responsabilidad y decisi\u00f3n y los resultados llegaron\u201d, resalt\u00f3.<\/p>\n\n<p>Se\u00f1al\u00f3 que se recibieron m\u00e1s de 5,200 vuelos cada mes, con ocho de cada 10 asientos llenos. Durante 2021, comenzaron a llegar los cruceros, y durante el \u00faltimo trimestre del a\u00f1o se recuper\u00f3 el 61 % de los cruceristas y se inaugur\u00f3 Taino Bay, un nuevo puerto de cruceros en la ciudad de Puerto Plata.<\/p>\n\n<p>Adem\u00e1s, dijo que en 2021 se aprobaron 47 nuevos proyectos tur\u00edsticos con 9,423 habitaciones y 1,700 millones de d\u00f3lares en inversi\u00f3n. &#8220;Esto, junto a las m\u00e1s de 8,000 habitaciones ya en construcci\u00f3n nos prepara para el fuerte crecimiento que nos espera en los pr\u00f3ximos tres a\u00f1os&#8221;, dijo.<\/p>\n\n<p>Indic\u00f3 que durante 2021 se retomaron 21 proyectos de infraestructura tur\u00edstica por un valor de 965 millones de d\u00f3lares, se iniciaron nueve proyectos en los principales polos, como el malec\u00f3n de cabrera, remozamiento de Laguna Gri-Gri, y varias inversiones en playas, como Playa Las Galeras, Playa Esmeralda, Playa Macao, Playa Guayacanes, y en el sur, Playa los Patos y Playa el Quemaito.<\/p>\n\n<p>Fuente: Diario Libre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica,\u00a0Luis Abinader, dijo este domingo que el\u00a0desarrollo tur\u00edstico\u00a0de\u00a0Pedernales\u00a0es una de las apuestas m\u00e1s importantes de su gesti\u00f3n, porque, de acuerdo al mandatario, transformar\u00e1 la vida de miles de personas de la provincia de\u00a0Pedernales\u00a0y de toda la&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[149],"tags":[],"class_list":["post-5616","post","type-post","status-publish","format-standard","hentry","category-investment-in-dr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados<\/title>\n<meta name=\"description\" content=\"Work to begin on the first hotels in Pedernales in mid-2022\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados\" \/>\n<meta property=\"og:description\" content=\"Work to begin on the first hotels in Pedernales in mid-2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"DMK Abogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DMKAbogados\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T14:02:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T19:11:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2016\/07\/img-edificio-dmk-abogados-blur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fuente Externa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DMKAbogados\" \/>\n<meta name=\"twitter:site\" content=\"@DMKAbogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fuente Externa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\"},\"author\":{\"name\":\"Fuente Externa\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2\"},\"headline\":\"Work to begin on the first hotels in Pedernales in mid-2022\",\"datePublished\":\"2022-02-28T14:02:54+00:00\",\"dateModified\":\"2022-05-09T19:11:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\"},\"wordCount\":773,\"publisher\":{\"@id\":\"https:\/\/dmklawyers.com\/#organization\"},\"articleSection\":[\"Investment in DR\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\",\"url\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\",\"name\":\"Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados\",\"isPartOf\":{\"@id\":\"https:\/\/dmklawyers.com\/#website\"},\"datePublished\":\"2022-02-28T14:02:54+00:00\",\"dateModified\":\"2022-05-09T19:11:04+00:00\",\"description\":\"Work to begin on the first hotels in Pedernales in mid-2022\",\"breadcrumb\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dmklawyers.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Work to begin on the first hotels in Pedernales in mid-2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dmklawyers.com\/#website\",\"url\":\"https:\/\/dmklawyers.com\/\",\"name\":\"DMK Abogados\",\"description\":\"Firma de abogados l\u00edder (TOP-ranked) en la Rep\u00fablica Dominicana\",\"publisher\":{\"@id\":\"https:\/\/dmklawyers.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dmklawyers.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dmklawyers.com\/#organization\",\"name\":\"DMK Abogados\",\"url\":\"https:\/\/dmklawyers.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg\",\"contentUrl\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg\",\"width\":100,\"height\":100,\"caption\":\"DMK Abogados\"},\"image\":{\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DMKAbogados\/\",\"https:\/\/x.com\/DMKAbogados\",\"https:\/\/www.instagram.com\/dmkabogados\/\",\"https:\/\/www.linkedin.com\/company\/dmk-lawyers\/\",\"https:\/\/www.youtube.com\/channel\/UCBYQz9qoWkTyesJ_IOqyzYQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2\",\"name\":\"Fuente Externa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif\",\"contentUrl\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif\",\"caption\":\"Fuente Externa\"},\"url\":\"https:\/\/dmklawyers.com\/en\/author\/fe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados","description":"Work to begin on the first hotels in Pedernales in mid-2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/","og_locale":"en_US","og_type":"article","og_title":"Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados","og_description":"Work to begin on the first hotels in Pedernales in mid-2022","og_url":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/","og_site_name":"DMK Abogados","article_publisher":"https:\/\/www.facebook.com\/DMKAbogados\/","article_published_time":"2022-02-28T14:02:54+00:00","article_modified_time":"2022-05-09T19:11:04+00:00","og_image":[{"width":2000,"height":600,"url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2016\/07\/img-edificio-dmk-abogados-blur.jpg","type":"image\/jpeg"}],"author":"Fuente Externa","twitter_card":"summary_large_image","twitter_creator":"@DMKAbogados","twitter_site":"@DMKAbogados","twitter_misc":{"Written by":"Fuente Externa","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#article","isPartOf":{"@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/"},"author":{"name":"Fuente Externa","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2"},"headline":"Work to begin on the first hotels in Pedernales in mid-2022","datePublished":"2022-02-28T14:02:54+00:00","dateModified":"2022-05-09T19:11:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/"},"wordCount":773,"publisher":{"@id":"https:\/\/dmklawyers.com\/#organization"},"articleSection":["Investment in DR"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/","url":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/","name":"Work to begin on the first hotels in Pedernales in mid-2022 - DMK Abogados","isPartOf":{"@id":"https:\/\/dmklawyers.com\/#website"},"datePublished":"2022-02-28T14:02:54+00:00","dateModified":"2022-05-09T19:11:04+00:00","description":"Work to begin on the first hotels in Pedernales in mid-2022","breadcrumb":{"@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dmklawyers.com\/en\/work-to-begin-on-the-first-hotels-in-pedernales-in-mid-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dmklawyers.com\/en\/"},{"@type":"ListItem","position":2,"name":"Work to begin on the first hotels in Pedernales in mid-2022"}]},{"@type":"WebSite","@id":"https:\/\/dmklawyers.com\/#website","url":"https:\/\/dmklawyers.com\/","name":"DMK Abogados","description":"Firma de abogados l\u00edder (TOP-ranked) en la Rep\u00fablica Dominicana","publisher":{"@id":"https:\/\/dmklawyers.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dmklawyers.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dmklawyers.com\/#organization","name":"DMK Abogados","url":"https:\/\/dmklawyers.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/","url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg","contentUrl":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg","width":100,"height":100,"caption":"DMK Abogados"},"image":{"@id":"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DMKAbogados\/","https:\/\/x.com\/DMKAbogados","https:\/\/www.instagram.com\/dmkabogados\/","https:\/\/www.linkedin.com\/company\/dmk-lawyers\/","https:\/\/www.youtube.com\/channel\/UCBYQz9qoWkTyesJ_IOqyzYQ"]},{"@type":"Person","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2","name":"Fuente Externa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/image\/","url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif","contentUrl":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif","caption":"Fuente Externa"},"url":"https:\/\/dmklawyers.com\/en\/author\/fe\/"}]}},"taxonomy_info":{"category":[{"value":149,"label":"Investment in DR"}]},"featured_image_src_large":false,"author_info":{"display_name":"Fuente Externa","author_link":"https:\/\/dmklawyers.com\/en\/author\/fe\/"},"comment_info":0,"category_info":[{"term_id":149,"name":"Investment in DR","slug":"investment-in-dr","term_group":0,"term_taxonomy_id":149,"taxonomy":"category","description":"","parent":0,"count":703,"filter":"raw","cat_ID":149,"category_count":703,"category_description":"","cat_name":"Investment in DR","category_nicename":"investment-in-dr","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/comments?post=5616"}],"version-history":[{"count":2,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5616\/revisions"}],"predecessor-version":[{"id":6926,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5616\/revisions\/6926"}],"wp:attachment":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/media?parent=5616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/categories?post=5616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/tags?post=5616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}