{"id":5613,"date":"2022-02-28T14:06:57","date_gmt":"2022-02-28T14:06:57","guid":{"rendered":"https:\/\/www.dmklawyers.com\/?p=5613"},"modified":"2022-05-09T19:11:04","modified_gmt":"2022-05-09T19:11:04","slug":"free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader","status":"publish","type":"post","link":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/","title":{"rendered":"Free zones are one of the main pillars of the economy, says Abinader"},"content":{"rendered":"\n<p>Durante su rendici\u00f3n de cuentas en 2022, el presidente\u00a0Luis Abinader\u00a0dijo hoy que las\u00a0zonas francas\u00a0constituyen uno de los principales pilares de la\u00a0econom\u00eda\u00a0dominicana, se\u00f1alando que han sido un factor determinante para acelerar la recuperaci\u00f3n econ\u00f3mica.<\/p>\n\n<p>\u201cHemos tenido un crecimiento interanual enero\u2013diciembre del 20.3 % por ciento respecto al a\u00f1o 2020, con una inversi\u00f3n acumulada de 5,189 millones de d\u00f3lares, la mayor cantidad en los \u00faltimos nueve a\u00f1os\u201d, explic\u00f3.<\/p>\n\n<p>Adem\u00e1s, indic\u00f3 que, al cierre de 2021, existen ya 734 empresas en operaciones, distribuidas en 79 parques. Asimismo, ese a\u00f1o se aprob\u00f3 la mayor cantidad de empresas en la \u00faltima d\u00e9cada, totalizando 100 empresas aprobadas, para un aumento del 156 % en comparaci\u00f3n con el 2020.<\/p>\n\n<p>\u201cEstas proyectan una inversi\u00f3n de 230.6 millones de d\u00f3lares y la generaci\u00f3n de 12,575 empleos directos. Asimismo, se aprob\u00f3 la instalaci\u00f3n de seis parques industriales, que proyectan 53.6 millones de d\u00f3lares de inversi\u00f3n y la generaci\u00f3n de 7,719 empleos directos\u201d, explic\u00f3.<\/p>\n\n<p>Se\u00f1al\u00f3 que esto permiti\u00f3 que las exportaciones de\u00a0zonas francas\u00a0hayan ascendido a 7,177 millones de d\u00f3lares, representando el 60.4 % del total exportado y contribuyendo en un 67.5 % al crecimiento de las exportaciones totales.<\/p>\n\n<p>Precis\u00f3 que, en todos los meses de 2021, se export\u00f3 por encima del promedio hist\u00f3rico mensual, siendo marzo el mes de mayor volumen con cerca de 670 millones de d\u00f3lares.<\/p>\n\n<p>\u201cLas\u00a0zonas francas\u00a0se mantienen como una de las actividades productivas de mayor aporte de empleo directo en el pa\u00eds, siendo el primer sector econ\u00f3mico en volver a los niveles de empleo previos a la pandemia\u201d, apunt\u00f3.<\/p>\n\n<p>Abinader a\u00f1adi\u00f3 que, en la actualidad, las\u00a0zonas francas\u00a0registraron cerca de 182,700 empleos directos, cifra r\u00e9cord para los \u00faltimos 17 a\u00f1os. Esto representa un incremento de 8.6 % respecto al a\u00f1o 2020.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Actividad minera<\/strong><\/h3>\n\n<p>El presidente precis\u00f3 que la actividad minera continu\u00f3 siendo el rubro de mayor exportaci\u00f3n del pa\u00eds. Alrededor del 20 % de las cifras totales de exportaciones corresponden a productos mineros. Entre enero y diciembre del 2021, solo de oro el pa\u00eds export\u00f3 m\u00e1s de 1,800 millones de d\u00f3lares.<\/p>\n\n<p>\u201cEsta administraci\u00f3n cree en fomentar una industria minera sostenible que opere con los m\u00e1s altos estandartes del mundo, que garantice el medioambiente, la convivencia pac\u00edfica con las comunidades y que los recursos producidos sirvan para lograr una verdadera transformaci\u00f3n en la vida de las familias que residen en estas zonas\u201d, resalt\u00f3.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Mipymes<\/strong><\/h3>\n\n<p>Abinader a\u00f1adi\u00f3 que el apoyo al sector de las\u00a0mipymes\u00a0ha permitido que en el 2021 se formalizaran 12,721 nuevas micro, peque\u00f1as y medianas empresas, con lo que eso supone en impacto de empleo y actividad econ\u00f3mica local.<\/p>\n\n<p>Destac\u00f3 la apuesta que este gobierno est\u00e1 haciendo por el\u00a0cooperativismo.<\/p>\n\n<p>\u201cQueremos que el tejido industrial y asociativo crezca en todo el pa\u00eds, se una y resista mejor cualquier dificultad desde los peque\u00f1os productores del campo, o las\u00a0mipymes\u00a0de las ciudades como colmados, salones de belleza, artesanos, taxistas y muchos otros sectores\u201d, expres\u00f3.<\/p>\n\n<p>Dijo que al llegar al gobierno hab\u00eda 743 cooperativas en todo el pa\u00eds. Indic\u00f3 que solo en el 2021 se conformaron 808 cooperativas integradas por 35,244 socios y est\u00e1n diseminadas en las 32 provincias del pa\u00eds en 129 municipios y en 177 distritos municipales.<\/p>\n\n<p>\u201cEntre ellas 210 cooperativas de producci\u00f3n, trabajo y servicios m\u00faltiples, ocho cooperativas de salones y seis de peluqueros en poblaciones distintas. Tambi\u00e9n, 26 cooperativas de pescadores. Pero tambi\u00e9n 264 cooperativas agropecuarias que agrupan a 16,104 productores, criadores y ganaderos\u201d, explic\u00f3.<\/p>\n\n<p>Fuente: Diario Libre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante su rendici\u00f3n de cuentas en 2022, el presidente\u00a0Luis Abinader\u00a0dijo hoy que las\u00a0zonas francas\u00a0constituyen uno de los principales pilares de la\u00a0econom\u00eda\u00a0dominicana, se\u00f1alando que han sido un factor determinante para acelerar la recuperaci\u00f3n econ\u00f3mica. \u201cHemos tenido un crecimiento interanual enero\u2013diciembre del&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[149],"tags":[],"class_list":["post-5613","post","type-post","status-publish","format-standard","hentry","category-investment-in-dr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados<\/title>\n<meta name=\"description\" content=\"Free zones are one of the main pillars of the economy, says Abinader\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados\" \/>\n<meta property=\"og:description\" content=\"Free zones are one of the main pillars of the economy, says Abinader\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\" \/>\n<meta property=\"og:site_name\" content=\"DMK Abogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DMKAbogados\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T14:06:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T19:11:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2016\/07\/img-edificio-dmk-abogados-blur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fuente Externa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DMKAbogados\" \/>\n<meta name=\"twitter:site\" content=\"@DMKAbogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fuente Externa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\"},\"author\":{\"name\":\"Fuente Externa\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2\"},\"headline\":\"Free zones are one of the main pillars of the economy, says Abinader\",\"datePublished\":\"2022-02-28T14:06:57+00:00\",\"dateModified\":\"2022-05-09T19:11:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\"},\"wordCount\":597,\"publisher\":{\"@id\":\"https:\/\/dmklawyers.com\/#organization\"},\"articleSection\":[\"Investment in DR\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\",\"url\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\",\"name\":\"Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados\",\"isPartOf\":{\"@id\":\"https:\/\/dmklawyers.com\/#website\"},\"datePublished\":\"2022-02-28T14:06:57+00:00\",\"dateModified\":\"2022-05-09T19:11:04+00:00\",\"description\":\"Free zones are one of the main pillars of the economy, says Abinader\",\"breadcrumb\":{\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dmklawyers.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free zones are one of the main pillars of the economy, says Abinader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dmklawyers.com\/#website\",\"url\":\"https:\/\/dmklawyers.com\/\",\"name\":\"DMK Abogados\",\"description\":\"Firma de abogados l\u00edder (TOP-ranked) en la Rep\u00fablica Dominicana\",\"publisher\":{\"@id\":\"https:\/\/dmklawyers.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dmklawyers.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dmklawyers.com\/#organization\",\"name\":\"DMK Abogados\",\"url\":\"https:\/\/dmklawyers.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg\",\"contentUrl\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg\",\"width\":100,\"height\":100,\"caption\":\"DMK Abogados\"},\"image\":{\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DMKAbogados\/\",\"https:\/\/x.com\/DMKAbogados\",\"https:\/\/www.instagram.com\/dmkabogados\/\",\"https:\/\/www.linkedin.com\/company\/dmk-lawyers\/\",\"https:\/\/www.youtube.com\/channel\/UCBYQz9qoWkTyesJ_IOqyzYQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2\",\"name\":\"Fuente Externa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dmklawyers.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif\",\"contentUrl\":\"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif\",\"caption\":\"Fuente Externa\"},\"url\":\"https:\/\/dmklawyers.com\/en\/author\/fe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados","description":"Free zones are one of the main pillars of the economy, says Abinader","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/","og_locale":"en_US","og_type":"article","og_title":"Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados","og_description":"Free zones are one of the main pillars of the economy, says Abinader","og_url":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/","og_site_name":"DMK Abogados","article_publisher":"https:\/\/www.facebook.com\/DMKAbogados\/","article_published_time":"2022-02-28T14:06:57+00:00","article_modified_time":"2022-05-09T19:11:04+00:00","og_image":[{"width":2000,"height":600,"url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2016\/07\/img-edificio-dmk-abogados-blur.jpg","type":"image\/jpeg"}],"author":"Fuente Externa","twitter_card":"summary_large_image","twitter_creator":"@DMKAbogados","twitter_site":"@DMKAbogados","twitter_misc":{"Written by":"Fuente Externa","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#article","isPartOf":{"@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/"},"author":{"name":"Fuente Externa","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2"},"headline":"Free zones are one of the main pillars of the economy, says Abinader","datePublished":"2022-02-28T14:06:57+00:00","dateModified":"2022-05-09T19:11:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/"},"wordCount":597,"publisher":{"@id":"https:\/\/dmklawyers.com\/#organization"},"articleSection":["Investment in DR"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/","url":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/","name":"Free zones are one of the main pillars of the economy, says Abinader - DMK Abogados","isPartOf":{"@id":"https:\/\/dmklawyers.com\/#website"},"datePublished":"2022-02-28T14:06:57+00:00","dateModified":"2022-05-09T19:11:04+00:00","description":"Free zones are one of the main pillars of the economy, says Abinader","breadcrumb":{"@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dmklawyers.com\/en\/free-zones-are-one-of-the-main-pillars-of-the-economy-says-abinader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dmklawyers.com\/en\/"},{"@type":"ListItem","position":2,"name":"Free zones are one of the main pillars of the economy, says Abinader"}]},{"@type":"WebSite","@id":"https:\/\/dmklawyers.com\/#website","url":"https:\/\/dmklawyers.com\/","name":"DMK Abogados","description":"Firma de abogados l\u00edder (TOP-ranked) en la Rep\u00fablica Dominicana","publisher":{"@id":"https:\/\/dmklawyers.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dmklawyers.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dmklawyers.com\/#organization","name":"DMK Abogados","url":"https:\/\/dmklawyers.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/","url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg","contentUrl":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/04\/logo-dmk-30anos_2.svg","width":100,"height":100,"caption":"DMK Abogados"},"image":{"@id":"https:\/\/dmklawyers.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DMKAbogados\/","https:\/\/x.com\/DMKAbogados","https:\/\/www.instagram.com\/dmkabogados\/","https:\/\/www.linkedin.com\/company\/dmk-lawyers\/","https:\/\/www.youtube.com\/channel\/UCBYQz9qoWkTyesJ_IOqyzYQ"]},{"@type":"Person","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/ea8cb9808cd835658a198ff992ae79b2","name":"Fuente Externa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dmklawyers.com\/#\/schema\/person\/image\/","url":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif","contentUrl":"https:\/\/dmklawyers.com\/wp-content\/uploads\/2022\/05\/logo-dmk-30anos.gif","caption":"Fuente Externa"},"url":"https:\/\/dmklawyers.com\/en\/author\/fe\/"}]}},"taxonomy_info":{"category":[{"value":149,"label":"Investment in DR"}]},"featured_image_src_large":false,"author_info":{"display_name":"Fuente Externa","author_link":"https:\/\/dmklawyers.com\/en\/author\/fe\/"},"comment_info":0,"category_info":[{"term_id":149,"name":"Investment in DR","slug":"investment-in-dr","term_group":0,"term_taxonomy_id":149,"taxonomy":"category","description":"","parent":0,"count":703,"filter":"raw","cat_ID":149,"category_count":703,"category_description":"","cat_name":"Investment in DR","category_nicename":"investment-in-dr","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/comments?post=5613"}],"version-history":[{"count":2,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5613\/revisions"}],"predecessor-version":[{"id":6925,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/posts\/5613\/revisions\/6925"}],"wp:attachment":[{"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/media?parent=5613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/categories?post=5613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dmklawyers.com\/en\/wp-json\/wp\/v2\/tags?post=5613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}